{"id":18955,"date":"2025-12-25T21:15:44","date_gmt":"2025-12-25T21:15:44","guid":{"rendered":"https:\/\/dackel.ch\/events\/esposizione-cac-per-giovani-e-veterani-4\/"},"modified":"2026-05-13T04:54:49","modified_gmt":"2026-05-13T04:54:49","slug":"esposizione-cac-per-giovani-e-veterani-4","status":"publish","type":"ajde_events","link":"https:\/\/dackel.ch\/it\/events\/esposizione-cac-per-giovani-e-veterani-4\/","title":{"rendered":"Esposizione CAC per giovani e veterani"},"content":{"rendered":"<p>Luogo: Niederhelfenschwil<br \/>\nwww.dackel-ost.ch<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"tags":[],"event_type":[53],"event_type_2":[],"class_list":["post-18955","ajde_events","type-ajde_events","status-publish","hentry","event_type-ausstellungen"],"_links":{"self":[{"href":"https:\/\/dackel.ch\/it\/wp-json\/wp\/v2\/ajde_events\/18955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dackel.ch\/it\/wp-json\/wp\/v2\/ajde_events"}],"about":[{"href":"https:\/\/dackel.ch\/it\/wp-json\/wp\/v2\/types\/ajde_events"}],"author":[{"embeddable":true,"href":"https:\/\/dackel.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dackel.ch\/it\/wp-json\/wp\/v2\/comments?post=18955"}],"wp:attachment":[{"href":"https:\/\/dackel.ch\/it\/wp-json\/wp\/v2\/media?parent=18955"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dackel.ch\/it\/wp-json\/wp\/v2\/tags?post=18955"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/dackel.ch\/it\/wp-json\/wp\/v2\/event_type?post=18955"},{"taxonomy":"event_type_2","embeddable":true,"href":"https:\/\/dackel.ch\/it\/wp-json\/wp\/v2\/event_type_2?post=18955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}